{"id":1591,"date":"2026-03-27T20:43:30","date_gmt":"2026-03-27T23:43:30","guid":{"rendered":"https:\/\/nossapauta.com.br\/?p=1591"},"modified":"2026-03-27T20:43:32","modified_gmt":"2026-03-27T23:43:32","slug":"o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia","status":"publish","type":"post","link":"https:\/\/nossapauta.com.br\/index.php\/2026\/03\/27\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\/","title":{"rendered":"O ministro do Supremo Tribunal Federal, Andr\u00e9 Mendon\u00e7a, acaba de receber uma informa\u00e7\u00e3o considerada sens\u00edvel nos bastidores de Bras\u00edlia."},"content":{"rendered":"\n<p>De acordo com apura\u00e7\u00f5es preliminares, trata-se de um poss\u00edvel depoimento ou den\u00fancia envolvendo nomes de grande relev\u00e2ncia pol\u00edtica, o que j\u00e1 movimenta o cen\u00e1rio jur\u00eddico e pol\u00edtico nacional.<br>Ainda n\u00e3o h\u00e1 confirma\u00e7\u00e3o oficial sobre o conte\u00fado detalhado da den\u00fancia, mas fontes indicam que o material pode envolver figuras de alto escal\u00e3o \u2014 os chamados \u201cpeixes grandes\u201d \u2014 e poder\u00e1 ter desdobramentos significativos nos pr\u00f3ximos dias.<br>A equipe do ministro mant\u00e9m sigilo absoluto sobre o caso neste momento, o que \u00e9 comum em situa\u00e7\u00f5es que envolvem investiga\u00e7\u00f5es delicadas ou poss\u00edveis processos em fase inicial.<br>Especialistas apontam que, dependendo da consist\u00eancia das informa\u00e7\u00f5es apresentadas, o caso pode:<br>Dar origem a novas investiga\u00e7\u00f5es;<br>Ser encaminhado \u00e0 Procuradoria-Geral da Rep\u00fablica;<br>Ou at\u00e9 gerar abertura de inqu\u00e9rito no STF.<br>A expectativa agora \u00e9 por um posicionamento oficial nas pr\u00f3ximas horas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ministro STF Andr\u00e9 Mendon\u00e7a <\/p>\n","protected":false},"author":2,"featured_media":1592,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O ministro do Supremo Tribunal Federal, Andr\u00e9 Mendon\u00e7a, acaba de receber uma informa\u00e7\u00e3o considerada sens\u00edvel nos bastidores de Bras\u00edlia. - Portal Nossa Pauta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nossapauta.com.br\/index.php\/2026\/03\/27\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O ministro do Supremo Tribunal Federal, Andr\u00e9 Mendon\u00e7a, acaba de receber uma informa\u00e7\u00e3o considerada sens\u00edvel nos bastidores de Bras\u00edlia. - Portal Nossa Pauta\" \/>\n<meta property=\"og:description\" content=\"Ministro STF Andr\u00e9 Mendon\u00e7a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nossapauta.com.br\/index.php\/2026\/03\/27\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal Nossa Pauta\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-27T23:43:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-27T23:43:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nossapauta.com.br\/wp-content\/uploads\/2026\/03\/Photo_1774652730092.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andr\u00e9 Mesquita\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NossaPautaNews\" \/>\n<meta name=\"twitter:site\" content=\"@NossaPautaNews\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andr\u00e9 Mesquita\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nossapauta.com.br\\\/index.php\\\/2026\\\/03\\\/27\\\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nossapauta.com.br\\\/index.php\\\/2026\\\/03\\\/27\\\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\\\/\"},\"author\":{\"name\":\"Andr\u00e9 Mesquita\",\"@id\":\"https:\\\/\\\/nossapauta.com.br\\\/#\\\/schema\\\/person\\\/d746bb0b099fa23efec4671408b19088\"},\"headline\":\"O ministro do Supremo Tribunal Federal, Andr\u00e9 Mendon\u00e7a, acaba de receber uma informa\u00e7\u00e3o considerada sens\u00edvel nos bastidores de Bras\u00edlia.\",\"datePublished\":\"2026-03-27T23:43:30+00:00\",\"dateModified\":\"2026-03-27T23:43:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nossapauta.com.br\\\/index.php\\\/2026\\\/03\\\/27\\\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\\\/\"},\"wordCount\":177,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/nossapauta.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nossapauta.com.br\\\/index.php\\\/2026\\\/03\\\/27\\\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nossapauta.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Photo_1774652730092.jpg\",\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/nossapauta.com.br\\\/index.php\\\/2026\\\/03\\\/27\\\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nossapauta.com.br\\\/index.php\\\/2026\\\/03\\\/27\\\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\\\/\",\"url\":\"https:\\\/\\\/nossapauta.com.br\\\/index.php\\\/2026\\\/03\\\/27\\\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\\\/\",\"name\":\"O ministro do Supremo Tribunal Federal, Andr\u00e9 Mendon\u00e7a, acaba de receber uma informa\u00e7\u00e3o considerada sens\u00edvel nos bastidores de Bras\u00edlia. - Portal Nossa Pauta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nossapauta.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nossapauta.com.br\\\/index.php\\\/2026\\\/03\\\/27\\\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nossapauta.com.br\\\/index.php\\\/2026\\\/03\\\/27\\\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nossapauta.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Photo_1774652730092.jpg\",\"datePublished\":\"2026-03-27T23:43:30+00:00\",\"dateModified\":\"2026-03-27T23:43:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nossapauta.com.br\\\/index.php\\\/2026\\\/03\\\/27\\\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nossapauta.com.br\\\/index.php\\\/2026\\\/03\\\/27\\\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nossapauta.com.br\\\/index.php\\\/2026\\\/03\\\/27\\\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nossapauta.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Photo_1774652730092.jpg\",\"contentUrl\":\"https:\\\/\\\/nossapauta.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Photo_1774652730092.jpg\",\"width\":720,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nossapauta.com.br\\\/index.php\\\/2026\\\/03\\\/27\\\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/nossapauta.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O ministro do Supremo Tribunal Federal, Andr\u00e9 Mendon\u00e7a, acaba de receber uma informa\u00e7\u00e3o considerada sens\u00edvel nos bastidores de Bras\u00edlia.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nossapauta.com.br\\\/#website\",\"url\":\"https:\\\/\\\/nossapauta.com.br\\\/\",\"name\":\"Nossa Pauta\",\"description\":\"Seu Portal de not\u00edcias que te atualiza.\",\"publisher\":{\"@id\":\"https:\\\/\\\/nossapauta.com.br\\\/#organization\"},\"alternateName\":\"Portal Nossa Pauta\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nossapauta.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nossapauta.com.br\\\/#organization\",\"name\":\"Portal Nossa Pauta\",\"url\":\"https:\\\/\\\/nossapauta.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nossapauta.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nossapauta.com.br\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/nossa_pauta_icone.png\",\"contentUrl\":\"https:\\\/\\\/nossapauta.com.br\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/nossa_pauta_icone.png\",\"width\":200,\"height\":186,\"caption\":\"Portal Nossa Pauta\"},\"image\":{\"@id\":\"https:\\\/\\\/nossapauta.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/NossaPautaNews\",\"https:\\\/\\\/instagram.com\\\/nossa_pauta\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nossapauta.com.br\\\/#\\\/schema\\\/person\\\/d746bb0b099fa23efec4671408b19088\",\"name\":\"Andr\u00e9 Mesquita\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/176a5646e67d1531cbf999621337619c32919d98f61cca6309822d3466db2a61?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/176a5646e67d1531cbf999621337619c32919d98f61cca6309822d3466db2a61?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/176a5646e67d1531cbf999621337619c32919d98f61cca6309822d3466db2a61?s=96&d=mm&r=g\",\"caption\":\"Andr\u00e9 Mesquita\"},\"url\":\"https:\\\/\\\/nossapauta.com.br\\\/index.php\\\/author\\\/andre\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O ministro do Supremo Tribunal Federal, Andr\u00e9 Mendon\u00e7a, acaba de receber uma informa\u00e7\u00e3o considerada sens\u00edvel nos bastidores de Bras\u00edlia. - Portal Nossa Pauta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nossapauta.com.br\/index.php\/2026\/03\/27\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\/","og_locale":"pt_BR","og_type":"article","og_title":"O ministro do Supremo Tribunal Federal, Andr\u00e9 Mendon\u00e7a, acaba de receber uma informa\u00e7\u00e3o considerada sens\u00edvel nos bastidores de Bras\u00edlia. - Portal Nossa Pauta","og_description":"Ministro STF Andr\u00e9 Mendon\u00e7a","og_url":"https:\/\/nossapauta.com.br\/index.php\/2026\/03\/27\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\/","og_site_name":"Portal Nossa Pauta","article_published_time":"2026-03-27T23:43:30+00:00","article_modified_time":"2026-03-27T23:43:32+00:00","og_image":[{"width":720,"height":960,"url":"https:\/\/nossapauta.com.br\/wp-content\/uploads\/2026\/03\/Photo_1774652730092.jpg","type":"image\/jpeg"}],"author":"Andr\u00e9 Mesquita","twitter_card":"summary_large_image","twitter_creator":"@NossaPautaNews","twitter_site":"@NossaPautaNews","twitter_misc":{"Escrito por":"Andr\u00e9 Mesquita","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nossapauta.com.br\/index.php\/2026\/03\/27\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\/#article","isPartOf":{"@id":"https:\/\/nossapauta.com.br\/index.php\/2026\/03\/27\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\/"},"author":{"name":"Andr\u00e9 Mesquita","@id":"https:\/\/nossapauta.com.br\/#\/schema\/person\/d746bb0b099fa23efec4671408b19088"},"headline":"O ministro do Supremo Tribunal Federal, Andr\u00e9 Mendon\u00e7a, acaba de receber uma informa\u00e7\u00e3o considerada sens\u00edvel nos bastidores de Bras\u00edlia.","datePublished":"2026-03-27T23:43:30+00:00","dateModified":"2026-03-27T23:43:32+00:00","mainEntityOfPage":{"@id":"https:\/\/nossapauta.com.br\/index.php\/2026\/03\/27\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\/"},"wordCount":177,"commentCount":0,"publisher":{"@id":"https:\/\/nossapauta.com.br\/#organization"},"image":{"@id":"https:\/\/nossapauta.com.br\/index.php\/2026\/03\/27\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\/#primaryimage"},"thumbnailUrl":"https:\/\/nossapauta.com.br\/wp-content\/uploads\/2026\/03\/Photo_1774652730092.jpg","articleSection":["Pol\u00edtica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nossapauta.com.br\/index.php\/2026\/03\/27\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nossapauta.com.br\/index.php\/2026\/03\/27\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\/","url":"https:\/\/nossapauta.com.br\/index.php\/2026\/03\/27\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\/","name":"O ministro do Supremo Tribunal Federal, Andr\u00e9 Mendon\u00e7a, acaba de receber uma informa\u00e7\u00e3o considerada sens\u00edvel nos bastidores de Bras\u00edlia. - Portal Nossa Pauta","isPartOf":{"@id":"https:\/\/nossapauta.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nossapauta.com.br\/index.php\/2026\/03\/27\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\/#primaryimage"},"image":{"@id":"https:\/\/nossapauta.com.br\/index.php\/2026\/03\/27\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\/#primaryimage"},"thumbnailUrl":"https:\/\/nossapauta.com.br\/wp-content\/uploads\/2026\/03\/Photo_1774652730092.jpg","datePublished":"2026-03-27T23:43:30+00:00","dateModified":"2026-03-27T23:43:32+00:00","breadcrumb":{"@id":"https:\/\/nossapauta.com.br\/index.php\/2026\/03\/27\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nossapauta.com.br\/index.php\/2026\/03\/27\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nossapauta.com.br\/index.php\/2026\/03\/27\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\/#primaryimage","url":"https:\/\/nossapauta.com.br\/wp-content\/uploads\/2026\/03\/Photo_1774652730092.jpg","contentUrl":"https:\/\/nossapauta.com.br\/wp-content\/uploads\/2026\/03\/Photo_1774652730092.jpg","width":720,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/nossapauta.com.br\/index.php\/2026\/03\/27\/o-ministro-do-supremo-tribunal-federal-andre-mendonca-acaba-de-receber-uma-informacao-considerada-sensivel-nos-bastidores-de-brasilia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/nossapauta.com.br\/"},{"@type":"ListItem","position":2,"name":"O ministro do Supremo Tribunal Federal, Andr\u00e9 Mendon\u00e7a, acaba de receber uma informa\u00e7\u00e3o considerada sens\u00edvel nos bastidores de Bras\u00edlia."}]},{"@type":"WebSite","@id":"https:\/\/nossapauta.com.br\/#website","url":"https:\/\/nossapauta.com.br\/","name":"Nossa Pauta","description":"Seu Portal de not\u00edcias que te atualiza.","publisher":{"@id":"https:\/\/nossapauta.com.br\/#organization"},"alternateName":"Portal Nossa Pauta","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nossapauta.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nossapauta.com.br\/#organization","name":"Portal Nossa Pauta","url":"https:\/\/nossapauta.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nossapauta.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/nossapauta.com.br\/wp-content\/uploads\/2025\/10\/nossa_pauta_icone.png","contentUrl":"https:\/\/nossapauta.com.br\/wp-content\/uploads\/2025\/10\/nossa_pauta_icone.png","width":200,"height":186,"caption":"Portal Nossa Pauta"},"image":{"@id":"https:\/\/nossapauta.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/NossaPautaNews","https:\/\/instagram.com\/nossa_pauta"]},{"@type":"Person","@id":"https:\/\/nossapauta.com.br\/#\/schema\/person\/d746bb0b099fa23efec4671408b19088","name":"Andr\u00e9 Mesquita","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/176a5646e67d1531cbf999621337619c32919d98f61cca6309822d3466db2a61?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/176a5646e67d1531cbf999621337619c32919d98f61cca6309822d3466db2a61?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/176a5646e67d1531cbf999621337619c32919d98f61cca6309822d3466db2a61?s=96&d=mm&r=g","caption":"Andr\u00e9 Mesquita"},"url":"https:\/\/nossapauta.com.br\/index.php\/author\/andre\/"}]}},"_links":{"self":[{"href":"https:\/\/nossapauta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nossapauta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nossapauta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nossapauta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nossapauta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1591"}],"version-history":[{"count":2,"href":"https:\/\/nossapauta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1591\/revisions"}],"predecessor-version":[{"id":1595,"href":"https:\/\/nossapauta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1591\/revisions\/1595"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nossapauta.com.br\/index.php\/wp-json\/wp\/v2\/media\/1592"}],"wp:attachment":[{"href":"https:\/\/nossapauta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nossapauta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nossapauta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}